{"id":162444,"date":"2026-04-17T21:02:41","date_gmt":"2026-04-17T21:02:41","guid":{"rendered":"https:\/\/business.udemy.com\/?post_type=resources&#038;p=162444"},"modified":"2026-04-17T21:02:43","modified_gmt":"2026-04-17T21:02:43","slug":"thanks","status":"publish","type":"resources","link":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/","title":{"rendered":"Thanks"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":162408,"menu_order":0,"template":"resources-thanks.php","categories":[],"resource_type":[10],"event_status":[],"class_list":["post-162444","resources","type-resources","status-publish","hentry","resource_type-thanks","post","without-featured-image"],"acf":{"choose_resource_hubs":[],"publish_to_selected_resource_hubs":[],"resource_topics":[],"custom_css":"","custom_js":"","headline":"Let the learning begin","recommended_resources_headline":"You may also be interested in","related_resources_group":"skills","video_cta_type":"","video_cta_action":"","marketo_custom_thank_you_message":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Thanks - Udemy Business<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/business.udemy.com\/tr\/resources\/connected-learning-ecosystem\/thanks\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thanks\" \/>\n<meta property=\"og:url\" content=\"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/\" \/>\n<meta property=\"og:site_name\" content=\"Udemy Business\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/udemy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T21:02:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/business.udemy.com\/wp-content\/uploads\/2023\/06\/udemy-business-organic-social-share-1200x630-refresh-2.png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@udemy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/resources\\\/connected-learning-ecosystem\\\/thanks\\\/\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/resources\\\/connected-learning-ecosystem\\\/thanks\\\/\",\"name\":\"Thanks - Udemy Business\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#website\"},\"datePublished\":\"2026-04-17T21:02:41+00:00\",\"dateModified\":\"2026-04-17T21:02:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/resources\\\/connected-learning-ecosystem\\\/thanks\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/business.udemy.com\\\/resources\\\/connected-learning-ecosystem\\\/thanks\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/resources\\\/connected-learning-ecosystem\\\/thanks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/resource-center\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Connected Learning Ecosystem\",\"item\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/resources\\\/connected-learning-ecosystem\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Thanks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/\",\"name\":\"Udemy Business\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#organization\",\"name\":\"Udemy Business\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/udemy-business-logo.svg\",\"contentUrl\":\"https:\\\/\\\/business.udemy.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/udemy-business-logo.svg\",\"width\":164,\"height\":28,\"caption\":\"Udemy Business\"},\"image\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udemy\",\"https:\\\/\\\/x.com\\\/udemy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/udemy\",\"https:\\\/\\\/www.instagram.com\\\/udemy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Thanks - Udemy Business","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/business.udemy.com\/tr\/resources\/connected-learning-ecosystem\/thanks\/","og_locale":"tr_TR","og_type":"article","og_title":"Thanks","og_url":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/","og_site_name":"Udemy Business","article_publisher":"https:\/\/www.facebook.com\/udemy","article_modified_time":"2026-04-17T21:02:43+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/business.udemy.com\/wp-content\/uploads\/2023\/06\/udemy-business-organic-social-share-1200x630-refresh-2.png.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@udemy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/","url":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/","name":"Thanks - Udemy Business","isPartOf":{"@id":"https:\/\/business.udemy.com\/tr\/#website"},"datePublished":"2026-04-17T21:02:41+00:00","dateModified":"2026-04-17T21:02:43+00:00","breadcrumb":{"@id":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/business.udemy.com\/resources\/connected-learning-ecosystem\/thanks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/business.udemy.com\/tr\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/business.udemy.com\/tr\/resource-center\/"},{"@type":"ListItem","position":3,"name":"The Connected Learning Ecosystem","item":"https:\/\/business.udemy.com\/tr\/resources\/connected-learning-ecosystem\/"},{"@type":"ListItem","position":4,"name":"Thanks"}]},{"@type":"WebSite","@id":"https:\/\/business.udemy.com\/tr\/#website","url":"https:\/\/business.udemy.com\/tr\/","name":"Udemy Business","description":"","publisher":{"@id":"https:\/\/business.udemy.com\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/business.udemy.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/business.udemy.com\/tr\/#organization","name":"Udemy Business","url":"https:\/\/business.udemy.com\/tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/business.udemy.com\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/business.udemy.com\/wp-content\/uploads\/2021\/04\/udemy-business-logo.svg","contentUrl":"https:\/\/business.udemy.com\/wp-content\/uploads\/2021\/04\/udemy-business-logo.svg","width":164,"height":28,"caption":"Udemy Business"},"image":{"@id":"https:\/\/business.udemy.com\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udemy","https:\/\/x.com\/udemy","https:\/\/www.linkedin.com\/company\/udemy","https:\/\/www.instagram.com\/udemy\/"]}]}},"_links":{"self":[{"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/resources\/162444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/types\/resources"}],"up":[{"embeddable":true,"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/resources\/162408"}],"wp:attachment":[{"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/media?parent=162444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/categories?post=162444"},{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/resource_type?post=162444"},{"taxonomy":"event_status","embeddable":true,"href":"https:\/\/business.udemy.com\/tr\/wp-json\/wp\/v2\/event_status?post=162444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}