{"id":352,"count":27,"description":"","link":"https:\/\/business.udemy.com\/blog\/leadership-management\/","name":"Leadership &amp; Management","slug":"leadership-management","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Leadership &amp; Management | The Source<\/title>\n<meta name=\"description\" content=\"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/business.udemy.com\/es-419\/blog\/leadership-management\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leadership &amp; Management | The Source\" \/>\n<meta property=\"og:description\" content=\"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/business.udemy.com\/blog\/leadership-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Udemy Business\" \/>\n<meta property=\"og:image\" content=\"https:\/\/business.udemy.com\/wp-content\/uploads\/2023\/06\/udemy-business-organic-social-share-1200x630-refresh-2.png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@udemy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/blog\\\/leadership-management\\\/\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/blog\\\/leadership-management\\\/\",\"name\":\"Leadership &amp; Management | The Source\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#website\"},\"description\":\"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/blog\\\/leadership-management\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/blog\\\/leadership-management\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liderazgo y administraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#website\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/\",\"name\":\"Udemy Business\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#organization\",\"name\":\"Udemy Business\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/business.udemy.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/udemy-business-logo.svg\",\"contentUrl\":\"https:\\\/\\\/business.udemy.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/udemy-business-logo.svg\",\"width\":164,\"height\":28,\"caption\":\"Udemy Business\"},\"image\":{\"@id\":\"https:\\\/\\\/business.udemy.com\\\/es-419\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udemy\",\"https:\\\/\\\/x.com\\\/udemy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/udemy\",\"https:\\\/\\\/www.instagram.com\\\/udemy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Leadership &amp; Management | The Source","description":"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/business.udemy.com\/es-419\/blog\/leadership-management\/","og_locale":"es_MX","og_type":"article","og_title":"Leadership &amp; Management | The Source","og_description":"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.","og_url":"https:\/\/business.udemy.com\/blog\/leadership-management\/","og_site_name":"Udemy Business","og_image":[{"width":1200,"height":630,"url":"https:\/\/business.udemy.com\/wp-content\/uploads\/2023\/06\/udemy-business-organic-social-share-1200x630-refresh-2.png.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@udemy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/business.udemy.com\/blog\/leadership-management\/","url":"https:\/\/business.udemy.com\/blog\/leadership-management\/","name":"Leadership &amp; Management | The Source","isPartOf":{"@id":"https:\/\/business.udemy.com\/es-419\/#website"},"description":"Actionable leadership insights to develop managers, lead change, and build high-performance cultures.","breadcrumb":{"@id":"https:\/\/business.udemy.com\/blog\/leadership-management\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/business.udemy.com\/blog\/leadership-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/business.udemy.com\/es-419\/"},{"@type":"ListItem","position":2,"name":"Liderazgo y administraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/business.udemy.com\/es-419\/#website","url":"https:\/\/business.udemy.com\/es-419\/","name":"Udemy Business","description":"","publisher":{"@id":"https:\/\/business.udemy.com\/es-419\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/business.udemy.com\/es-419\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/business.udemy.com\/es-419\/#organization","name":"Udemy Business","url":"https:\/\/business.udemy.com\/es-419\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/business.udemy.com\/es-419\/#\/schema\/logo\/image\/","url":"https:\/\/business.udemy.com\/wp-content\/uploads\/2021\/04\/udemy-business-logo.svg","contentUrl":"https:\/\/business.udemy.com\/wp-content\/uploads\/2021\/04\/udemy-business-logo.svg","width":164,"height":28,"caption":"Udemy Business"},"image":{"@id":"https:\/\/business.udemy.com\/es-419\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udemy","https:\/\/x.com\/udemy","https:\/\/www.linkedin.com\/company\/udemy","https:\/\/www.instagram.com\/udemy\/"]}]}},"_links":{"self":[{"href":"https:\/\/business.udemy.com\/es-419\/wp-json\/wp\/v2\/categories\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/business.udemy.com\/es-419\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/business.udemy.com\/es-419\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/business.udemy.com\/es-419\/wp-json\/wp\/v2\/posts?categories=352"},{"href":"https:\/\/business.udemy.com\/es-419\/wp-json\/wp\/v2\/resources?categories=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}